{"id":1586,"date":"2024-10-10T15:24:14","date_gmt":"2024-10-10T15:24:14","guid":{"rendered":"https:\/\/www.urologues-opera.paris\/rein-et-ureteres\/"},"modified":"2025-07-17T15:22:47","modified_gmt":"2025-07-17T15:22:47","slug":"kidneys-ureters","status":"publish","type":"page","link":"https:\/\/www.urologues-opera.paris\/en\/kidneys-ureters\/","title":{"rendered":"Kidneys and Ureters"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":3,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"open","ping_status":"closed","template":"page-templates\/InternalPage.php","meta":{"footnotes":""},"class_list":["post-1586","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Kidneys and Ureters: Function and Disorders | Urology Paris Op\u00e9ra<\/title>\n<meta name=\"description\" content=\"The Urology Paris Op\u00e9ra group offers state-of-the-art medical facilities, accessible through partner institutions, ensuring high-quality care regardless of location.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.urologues-opera.paris\/en\/kidneys-ureters\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Kidneys and Ureters: Function and Disorders | Urology Paris Op\u00e9ra\" \/>\n<meta property=\"og:description\" content=\"The Urology Paris Op\u00e9ra group offers state-of-the-art medical facilities, accessible through partner institutions, ensuring high-quality care regardless of location.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.urologues-opera.paris\/en\/kidneys-ureters\/\" \/>\n<meta property=\"og:site_name\" content=\"Urologie Paris Op\u00e9ra\" \/>\n<meta property=\"article:modified_time\" content=\"2025-07-17T15:22:47+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.urologues-opera.paris\\\/en\\\/kidneys-ureters\\\/\",\"url\":\"https:\\\/\\\/www.urologues-opera.paris\\\/en\\\/kidneys-ureters\\\/\",\"name\":\"Kidneys and Ureters: Function and Disorders | Urology Paris Op\u00e9ra\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.urologues-opera.paris\\\/#website\"},\"datePublished\":\"2024-10-10T15:24:14+00:00\",\"dateModified\":\"2025-07-17T15:22:47+00:00\",\"description\":\"The Urology Paris Op\u00e9ra group offers state-of-the-art medical facilities, accessible through partner institutions, ensuring high-quality care regardless of location.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.urologues-opera.paris\\\/en\\\/kidneys-ureters\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.urologues-opera.paris\\\/en\\\/kidneys-ureters\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.urologues-opera.paris\\\/en\\\/kidneys-ureters\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.urologues-opera.paris\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Kidneys and Ureters\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.urologues-opera.paris\\\/#website\",\"url\":\"https:\\\/\\\/www.urologues-opera.paris\\\/\",\"name\":\"Urologie Paris Op\u00e9ra\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.urologues-opera.paris\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Kidneys and Ureters: Function and Disorders | Urology Paris Op\u00e9ra","description":"The Urology Paris Op\u00e9ra group offers state-of-the-art medical facilities, accessible through partner institutions, ensuring high-quality care regardless of location.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.urologues-opera.paris\/en\/kidneys-ureters\/","og_locale":"en_US","og_type":"article","og_title":"Kidneys and Ureters: Function and Disorders | Urology Paris Op\u00e9ra","og_description":"The Urology Paris Op\u00e9ra group offers state-of-the-art medical facilities, accessible through partner institutions, ensuring high-quality care regardless of location.","og_url":"https:\/\/www.urologues-opera.paris\/en\/kidneys-ureters\/","og_site_name":"Urologie Paris Op\u00e9ra","article_modified_time":"2025-07-17T15:22:47+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.urologues-opera.paris\/en\/kidneys-ureters\/","url":"https:\/\/www.urologues-opera.paris\/en\/kidneys-ureters\/","name":"Kidneys and Ureters: Function and Disorders | Urology Paris Op\u00e9ra","isPartOf":{"@id":"https:\/\/www.urologues-opera.paris\/#website"},"datePublished":"2024-10-10T15:24:14+00:00","dateModified":"2025-07-17T15:22:47+00:00","description":"The Urology Paris Op\u00e9ra group offers state-of-the-art medical facilities, accessible through partner institutions, ensuring high-quality care regardless of location.","breadcrumb":{"@id":"https:\/\/www.urologues-opera.paris\/en\/kidneys-ureters\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.urologues-opera.paris\/en\/kidneys-ureters\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.urologues-opera.paris\/en\/kidneys-ureters\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.urologues-opera.paris\/en\/"},{"@type":"ListItem","position":2,"name":"Kidneys and Ureters"}]},{"@type":"WebSite","@id":"https:\/\/www.urologues-opera.paris\/#website","url":"https:\/\/www.urologues-opera.paris\/","name":"Urologie Paris Op\u00e9ra","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.urologues-opera.paris\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/www.urologues-opera.paris\/en\/wp-json\/wp\/v2\/pages\/1586","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.urologues-opera.paris\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.urologues-opera.paris\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.urologues-opera.paris\/en\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.urologues-opera.paris\/en\/wp-json\/wp\/v2\/comments?post=1586"}],"version-history":[{"count":0,"href":"https:\/\/www.urologues-opera.paris\/en\/wp-json\/wp\/v2\/pages\/1586\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.urologues-opera.paris\/en\/wp-json\/wp\/v2\/media?parent=1586"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}